{"id":28379,"date":"2025-03-06T10:04:15","date_gmt":"2025-03-06T10:04:15","guid":{"rendered":"https:\/\/educare.design\/?post_type=product&#038;p=28379"},"modified":"2026-04-08T09:35:59","modified_gmt":"2026-04-08T09:35:59","slug":"vintage-female-pelvis","status":"publish","type":"product","link":"https:\/\/educare.design\/fr\/shop\/vintage-female-pelvis\/","title":{"rendered":"Le Bassin de la Femme"},"content":{"rendered":"<div id=\"fws_6a573fda64273\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Cat\u00e9gorie :<br \/>\n<em><a href=\"https:\/\/educare.design\/fr\/cat\/vin\/\" target=\"_blank\" rel=\"noopener\">Anatomie Vintage<\/a><\/em><br \/>\nSyst\u00e8me :<br \/>\n<em><a href=\"https:\/\/educare.design\/fr\/item\/reproductive-health\/\" target=\"_blank\" rel=\"noopener\">Sant\u00e9 Reproductive<\/a><\/em><\/p>\n<p>Disponible en <a href=\"https:\/\/educare.design\/fr\/posters\/\" target=\"_blank\" rel=\"noopener\">affiches imprim\u00e9es<\/a>, <a href=\"https:\/\/educare.design\/fr\/impressions-sur-toile\/\" target=\"_blank\" rel=\"noopener\">impressions sur toile<\/a> et imprimez-le vous-m\u00eame <a href=\"https:\/\/educare.design\/fr\/fichiers-pdf-numeriques\/\" target=\"_blank\" rel=\"noopener\">Fichiers PDF<\/a>. Parcourez la galerie d'images et zoomez pour voir les d\u00e9tails des diff\u00e9rentes options pour cette \u0153uvre d'art, y compris : <a href=\"https:\/\/educare.design\/fr\/sizes-types\/\" target=\"_blank\" rel=\"noopener\">types et tailles<\/a>. \u26a0\ufe0f <em>Les textes sur ces \u0153uvres sont en anglais et\/ou en latin m\u00e9dical uniquement.<\/em><\/p>\n<p><span style=\"color: #488693;\"><strong>\u2605\u2605\u2605\u2605\u2605<\/strong><\/span> <em>\u201cSuper nice contact with Kasper. Great quality and fast delivery.\u201d<\/em> - \ud83c\udde9\ud83c\uddea <a href=\"http:\/\/www.rekert.de\/\" target=\"_blank\" rel=\"noopener\">PhysioConcept Rekert<\/a><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Anatomie pelvienne classique, r\u00e9interpr\u00e9t\u00e9e \u2013 Le Bassin F\u00e9minin pr\u00e9sente une \u00e9tude anatomique d\u00e9taill\u00e9e de la structure osseuse pelvienne, inspir\u00e9e par la pr\u00e9cision et la sobri\u00e9t\u00e9 de la gravure m\u00e9dicale classique. La relation architecturale entre l\u2019ilium, l\u2019ischion et le pubis \u2014 ainsi que le sacrum, le coccyx et la structure ac\u00e9tabulaire \u2014 est rendue avec clart\u00e9, proportion et ma\u00eetrise du trait.<\/p>\n<p>Les r\u00e9f\u00e9rences num\u00e9rot\u00e9es sont plac\u00e9es directement sur l\u2019anatomie et correspondent \u00e0 un index circulaire entourant la figure. Cette structure radiale int\u00e8gre la nomenclature \u00e0 la composition elle-m\u00eame \u2014 permettant au marquage anatomique de renforcer l\u2019\u00e9quilibre visuel plut\u00f4t que de l\u2019interrompre.<\/p>\n<p>Historiquement, l\u2019illustration anatomique reposait sur un ombrage contr\u00f4l\u00e9 et un travail de contour m\u00e9ticuleux afin de communiquer profondeur et relations structurelles bien avant l\u2019\u00e8re de l\u2019imagerie m\u00e9dicale. Cette \u0153uvre honore cette tradition tout en s\u2019alignant sur le cadre contemporain d\u2019educare.design \u2014 typographie raffin\u00e9e, \u00e9quilibre spatial coh\u00e9rent et palette chromatique ma\u00eetris\u00e9e assurent une parfaite compatibilit\u00e9 entre collections modernes et heritage.<\/p>\n<p><strong>Disponible en \u00c9dition Claire et Noire.<\/strong><br \/>\nL\u2019\u0153uvre est propos\u00e9e en deux expressions distinctes :<br \/>\n<em>Une \u00e9dition neutre et douce qui s\u2019int\u00e8gre naturellement dans des int\u00e9rieurs cliniques scandinaves et minimalistes.<br \/>\nUne \u00e9dition noire qui introduit un contraste affirm\u00e9, transformant l\u2019anatomie classique en une d\u00e9claration visuelle de style galerie.<\/em><\/p>\n<p>Les deux versions conservent une pr\u00e9cision anatomique et une structure de mise en page identiques, permettant aux praticiens de choisir l\u2019atmosph\u00e8re la mieux adapt\u00e9e \u00e0 leur espace sans compromettre la clart\u00e9 p\u00e9dagogique. Le r\u00e9sultat n\u2019est ni purement vintage ni purement moderne. Il s\u2019agit d\u2019un h\u00e9ritage anatomique adapt\u00e9 aux environnements cliniques contemporains. Pr\u00e9sent\u00e9e seule, elle constitue un point focal raffin\u00e9. Associ\u00e9e \u00e0 des planches minimalistes, elle apporte une profondeur historique sans conflit visuel.<\/p>\n<p>Anatomie classique, r\u00e9\u00e9quilibr\u00e9e pour la pratique moderne.<\/p>\n<p><strong>Personnalisation gratuite avec le nom de votre clinique.<\/strong><br \/>\nPour cette \u0153uvre, nous vous proposons d\u2019ajouter gratuitement le nom de votre clinique (ou l\u2019adresse de votre site Web) ! Le nom remplacera le sous-titre actuel de l\u2019\u0153uvre (qui correspond aux noms latins de l\u2019anatomie) ; consultez une illustration de celui-ci dans la galerie d\u2019images.<\/p>\n<p><a href=\"https:\/\/youtu.be\/0DkUWC3Z-N8\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17589\" src=\"https:\/\/educare.design\/wp-content\/uploads\/2023\/12\/youtube-logo.png\" alt=\"\" width=\"55\" height=\"22\" \/><\/a>Voir ce graphique <a href=\"https:\/\/https:\/\/youtu.be\/0DkUWC3Z-N8\" target=\"_blank\" rel=\"noopener\">ici<\/a> sur YouTube.<\/p>\n<p><strong>Int\u00e9grez-le \u00e0 votre cabinet!<\/strong><br \/>\n<strong>\u2b07<\/strong> Commandez ici.<\/p>","protected":false},"featured_media":31921,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[61],"product_tag":[496,504],"class_list":["post-28379","product","type-product","status-publish","has-post-thumbnail","product_cat-vin","product_tag-reproductive-health","product_tag-spine-structure","first","instock","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/product\/28379","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/media\/31921"}],"wp:attachment":[{"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/media?parent=28379"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/product_brand?post=28379"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/product_cat?post=28379"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/educare.design\/fr\/wp-json\/wp\/v2\/product_tag?post=28379"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}