{"id":29471,"date":"2022-04-30T12:06:10","date_gmt":"2022-04-30T12:06:10","guid":{"rendered":"https:\/\/educare.design\/?post_type=product&#038;p=29471"},"modified":"2026-04-14T15:51:37","modified_gmt":"2026-04-14T15:51:37","slug":"mental-health-set","status":"publish","type":"product","link":"https:\/\/educare.design\/de\/shop\/mental-health-set\/","title":{"rendered":"Set Psychische Gesundheit"},"content":{"rendered":"<div id=\"fws_6a5750d385b4f\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone flex_gap_desktop_10px\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<p>Kategorie:<br \/>\n<em><a href=\"https:\/\/educare.design\/de\/cat\/sets-on-sale\/\" target=\"_blank\" rel=\"noopener\">Sets im Angebot<\/a><\/em><br \/>\nH\u00e4ufig kombiniert mit:<br \/>\n<em><a href=\"https:\/\/educare.design\/de\/shop\/cerebral-trilogy\/\" target=\"_blank\">Zerebrale Trilogie<\/a><\/em><\/p>\n<p>Sets im Angebot sind ausschlie\u00dflich als <a href=\"https:\/\/educare.design\/de\/posters\/\" target=\"_blank\" rel=\"noopener\">Posterdrucke<\/a> und <a href=\"https:\/\/educare.design\/de\/leinwanddrucke\/\" target=\"_blank\" rel=\"noopener\">Leinwanddrucke<\/a>. Die Sprachoptionen finden Sie auf den jeweiligen Produktseiten. \u26a0\ufe0f Hinweis: <em>Sets im Angebot k\u00f6nnen nicht mit Gutscheincodes erworben werden, und die enthaltenen Werke k\u00f6nnen nicht ausgetauscht werden.<\/em><\/p>\n<p><span style=\"color: #488693;\"><strong>\u2605\u2605\u2605\u2605\u2605<\/strong><\/span> <em>\u201eSehr sch\u00f6nes Design und schneller, professioneller Service. Beraten!\"<\/em> - \ud83c\udf10 <a href=\"https:\/\/g.co\/kgs\/6PEjjA\" target=\"_blank\" rel=\"noopener\">Google-Rezension<\/a><\/p>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p><span style=\"color: #b30885;\"><strong>Sparen Sie 25 % auf dieses 3er-Set.<\/strong><\/span><br \/>\nEine sorgf\u00e4ltig kuratierte dreiteilige Poster-Kollektion, die das Bewusstsein f\u00fcr psychische Gesundheit mit Sensibilit\u00e4t, Klarheit und St\u00e4rke f\u00f6rdert.<\/p>\n<p>Dieses Set thematisiert emotionales und psychisches Wohlbefinden durch kraftvolle visuelle Bildsprache und pr\u00e4gnante, reflektierende Botschaften. Anstatt psychische Belastungen zu dramatisieren, f\u00f6rdern die Werke Wahrnehmung, Dialog und Mitgef\u00fchl \u2014 und unterst\u00fctzen Fachkr\u00e4fte, die t\u00e4glich daran arbeiten, Stigmatisierung abzubauen und Verst\u00e4ndnis zu st\u00e4rken.<\/p>\n<p><a href=\"https:\/\/educare.design\/de\/shop\/in-control\/\" target=\"_blank\">In Kontrolle<\/a> untersucht das Zusammenspiel von Gedanken und Selbstwahrnehmung \u2014 und erinnert daran, dass mentale Resilienz aus Perspektive entsteht, nicht aus Unterdr\u00fcckung.<\/p>\n<p><a href=\"https:\/\/educare.design\/de\/shop\/smiling-depression\/\" target=\"_blank\">L\u00e4chelnde Depression<\/a> macht auf die Unsichtbarkeit seelischer Belastung aufmerksam \u2014 f\u00f6rdert Empathie und hinterfragt Annahmen dar\u00fcber, wie psychische Gesundheit \u201eaussehen\u201c sollte.<\/p>\n<p><a href=\"https:\/\/educare.design\/de\/shop\/its-okay\/\" target=\"_blank\">Es ist Okay<\/a> vermittelt eine einfache, aber zentrale Botschaft: Verletzlichkeit ist keine Schw\u00e4che. Kampf ist kein Versagen. Hilfe zu suchen ist St\u00e4rke.<\/p>\n<p>Gemeinsam schaffen die drei Werke einen ruhigen, menschenzentrierten Bewusstseinsraum, der zur Reflexion einl\u00e4dt, ohne zu konfrontieren. Die visuelle Gestaltung ist zur\u00fcckhaltend und zeitgem\u00e4\u00df \u2014 ideal f\u00fcr psychologische Praxen, psychiatrische Kliniken, physiotherapeutische Einrichtungen, Beratungsstellen und multidisziplin\u00e4re Gesundheitszentren.<\/p>\n<p>Dies ist keine dekorative Wandgestaltung.<br \/>\nEs ist visuelle F\u00fcrsprache \u2014 subtil, unterst\u00fctzend und fachlich fundiert.<\/p>\n<p>Setzen Sie ein mitf\u00fchlendes, modernes und verantwortungsvoll positioniertes Statement zur psychischen Gesundheit \u2014 und sparen Sie 25%.<\/p>\n<p><a href=\"https:\/\/youtu.be\/BA-M0ydYUeE\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-17589\" src=\"https:\/\/educare.design\/wp-content\/uploads\/2023\/12\/youtube-logo.png\" alt=\"\" width=\"55\" height=\"22\" \/><\/a>Dieses Set ansehen <a href=\"https:\/\/youtu.be\/BA-M0ydYUeE\" target=\"_blank\" rel=\"noopener\">hier<\/a> auf YouTube an.<\/p>\n<p><strong>Erg\u00e4nzen Sie Ihre Praxis mit diesem Set.<\/strong><br \/>\n<strong>\u2b07<\/strong> Hier bestellen.<\/p>","protected":false},"featured_media":29433,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[505],"product_tag":[],"class_list":["post-29471","product","type-product","status-publish","has-post-thumbnail","product_cat-sets-on-sale","first","instock","sale","shipping-taxable","purchasable","product-type-variable","has-default-attributes"],"acf":[],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/product\/29471","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/media\/29433"}],"wp:attachment":[{"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/media?parent=29471"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/product_brand?post=29471"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/product_cat?post=29471"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/educare.design\/de\/wp-json\/wp\/v2\/product_tag?post=29471"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}